{"id":1278,"date":"2022-03-01T01:01:36","date_gmt":"2022-02-28T23:01:36","guid":{"rendered":"https:\/\/www.in2sa.cat\/?p=1278"},"modified":"2022-03-22T12:53:05","modified_gmt":"2022-03-22T10:53:05","slug":"deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes","status":"publish","type":"post","link":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/","title":{"rendered":"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes?"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2.png\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-1275\" src=\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-300x300.png 300w, https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-1024x1024.png 1024w, https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-150x150.png 150w, https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-768x768.png 768w, https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-510x510.png 510w, https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Pr\u00f3ximamente saldr\u00e1 la primera convocatoria de ayudas del Kit Digital, con un presupuso de 3.067 millones de euros y que consta de bonos que van desde los 3.000 hasta los 12.000 euros para cada empresa que lo solicite y le sea concedido.<\/strong><\/p>\n<p>La problem\u00e1tica en la digitalizaci\u00f3n de una pyme sigue vigente y m\u00e1s del 67% de les pymes necesitan mejorar en alg\u00fan aspecto su proceso de digitalizaci\u00f3n empresarial, seg\u00fan el \u00faltimo estudio publicado en enero de 2022.<\/p>\n<p>Para fomentar la digitalizaci\u00f3n de les Pymes espa\u00f1olas, el Ministerio de Asuntos Econ\u00f3micos y Transformaci\u00f3n Digital ha lanzado el denominado\u00a0Kit Digital,\u00a0un\u00a0programa de ayudas econ\u00f3micas sin coste para las empresas.<\/p>\n<p>Desde Inform\u00e1tica Industrial os mostramos algunos de los aspectos en que una Pyme puede pedir las ayudas para digitalizarse y en las que estemos seguros que os podemos ayudar a hacerlas realidad:<\/p>\n<ul>\n<li><strong>Ciberseguridad:<\/strong> Actualmente esta es una de las grandes preocupaciones en muchas Pymes ya que los ciberataques se multiplican y tener un buen sistema de seguridad y de copias en la nube o de forma f\u00edsica puede garantizar a una Pyme que pueda seguir trabajando en cualquier momento y nunca pierda sus valiosos datos.<\/li>\n<li><strong>Mejorar la presencia en Internet:<\/strong> Hoy no es solo imprescindible tener una bona web sino que adem\u00e1s es necesario que esta est\u00e9 bien posicionada v\u00eda SEO de forma que la ayude a generar m\u00e1s tr\u00e1fico, m\u00e1s leads y m\u00e1s ventas. Para conseguirlo es necesario trabajar los contenidos de la web, el blog i las redes sociales.<\/li>\n<li><strong>Venta por e-commerce:<\/strong> No existen dudas que el comercio electr\u00f3nico que crece cada d\u00eda y que hay que asegurar que la experiencia de compra del consumidor sea la adecuada. Para ello debemos tener una\u00a0web bien dise\u00f1ada y con plataformas de pago adaptadas a las nuevas necesidades de los clientes, como Bizum o TPV virtuales. Sin descuidar los servicios de log\u00edstica y de resoluci\u00f3n de quejas o devoluciones.<\/li>\n<li><strong>Gesti\u00f3n de redes sociales:<\/strong> Aqu\u00ed se podr\u00e1n trabajar las posibilidades de comunicaci\u00f3n bidireccional que nos ofrecen estos nuevos canales, y aprovechar los servicios de atenci\u00f3n al cliente, resoluci\u00f3n de dudas o generaci\u00f3n de ventas desde Whatsapp, por citar alg\u00fan ejemplo.<\/li>\n<\/ul>\n<p>Seg\u00fan el CEO de IN2, Sr. Sebasti\u00e0 Pasqual, \u201c<em>en IN2 trabajamos para asesorar a las empresas de cu\u00e1les son las mejores soluciones en cualquiera de los aspectos anteriormente citados y lo hacemos de la mano de un equipo de expertos y de profesionales que nos permiten ofrecerles un asesoramiento previo y una posterior implementaci\u00f3n de la soluci\u00f3n que mejor se adapte a sus necesidades reales<\/em>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3ximamente saldr\u00e1 la primera convocatoria de ayudas del Kit Digital, con un presupuso de 3.067 millones de euros y que consta de bonos que van desde los 3.000 hasta los 12.000 euros para cada empresa que lo solicite y le sea concedido. La problem\u00e1tica en la digitalizaci\u00f3n de una pyme sigue vigente y m\u00e1s del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[169,39,38,40,112,41,43,184],"tags":[170,37,191,133],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes? - IN2 - Inform\u00e1tica industrial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes? - IN2 - Inform\u00e1tica industrial\" \/>\n<meta property=\"og:description\" content=\"Pr\u00f3ximamente saldr\u00e1 la primera convocatoria de ayudas del Kit Digital, con un presupuso de 3.067 millones de euros y que consta de bonos que van desde los 3.000 hasta los 12.000 euros para cada empresa que lo solicite y le sea concedido. La problem\u00e1tica en la digitalizaci\u00f3n de una pyme sigue vigente y m\u00e1s del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\" \/>\n<meta property=\"og:site_name\" content=\"IN2 - Inform\u00e1tica industrial\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T23:01:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-22T10:53:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-300x300.png\" \/>\n<meta name=\"author\" content=\"indosAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"indosAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\"},\"author\":{\"name\":\"indosAdmin\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#\/schema\/person\/4e69107c738f5383b8175d939415715f\"},\"headline\":\"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes?\",\"datePublished\":\"2022-02-28T23:01:36+00:00\",\"dateModified\":\"2022-03-22T10:53:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\"},\"wordCount\":464,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#organization\"},\"keywords\":[\"ciberseguridad\",\"in2\",\"kit digital\",\"pymes\"],\"articleSection\":[\"ciberseguridad\",\"clientes\",\"in2\",\"novedades\",\"Nuevas tecnolog\u00edas de la Informaci\u00f3n\",\"pymes del vall\u00e9s\",\"Seguridad\",\"transformaci\u00f3n digital\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\",\"url\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\",\"name\":\"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes? - IN2 - Inform\u00e1tica industrial\",\"isPartOf\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#website\"},\"datePublished\":\"2022-02-28T23:01:36+00:00\",\"dateModified\":\"2022-03-22T10:53:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.in2sa.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#website\",\"url\":\"https:\/\/www.in2sa.cat\/es\/\",\"name\":\"IN2 - Inform\u00e1tica industrial\",\"description\":\"Services for business\",\"publisher\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.in2sa.cat\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#organization\",\"name\":\"IN2 - Inform\u00e1tica industrial\",\"url\":\"https:\/\/www.in2sa.cat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png\",\"contentUrl\":\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png\",\"width\":287,\"height\":64,\"caption\":\"IN2 - Inform\u00e1tica industrial\"},\"image\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#\/schema\/person\/4e69107c738f5383b8175d939415715f\",\"name\":\"indosAdmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes? - IN2 - Inform\u00e1tica industrial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes? - IN2 - Inform\u00e1tica industrial","og_description":"Pr\u00f3ximamente saldr\u00e1 la primera convocatoria de ayudas del Kit Digital, con un presupuso de 3.067 millones de euros y que consta de bonos que van desde los 3.000 hasta los 12.000 euros para cada empresa que lo solicite y le sea concedido. La problem\u00e1tica en la digitalizaci\u00f3n de una pyme sigue vigente y m\u00e1s del [&hellip;]","og_url":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/","og_site_name":"IN2 - Inform\u00e1tica industrial","article_published_time":"2022-02-28T23:01:36+00:00","article_modified_time":"2022-03-22T10:53:05+00:00","og_image":[{"url":"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2022\/03\/proposta-nou-disseny-in2-300x300.png"}],"author":"indosAdmin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"indosAdmin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/#article","isPartOf":{"@id":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/"},"author":{"name":"indosAdmin","@id":"https:\/\/www.in2sa.cat\/es\/#\/schema\/person\/4e69107c738f5383b8175d939415715f"},"headline":"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes?","datePublished":"2022-02-28T23:01:36+00:00","dateModified":"2022-03-22T10:53:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/"},"wordCount":464,"commentCount":0,"publisher":{"@id":"https:\/\/www.in2sa.cat\/es\/#organization"},"keywords":["ciberseguridad","in2","kit digital","pymes"],"articleSection":["ciberseguridad","clientes","in2","novedades","Nuevas tecnolog\u00edas de la Informaci\u00f3n","pymes del vall\u00e9s","Seguridad","transformaci\u00f3n digital"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/","url":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/","name":"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes? - IN2 - Inform\u00e1tica industrial","isPartOf":{"@id":"https:\/\/www.in2sa.cat\/es\/#website"},"datePublished":"2022-02-28T23:01:36+00:00","dateModified":"2022-03-22T10:53:05+00:00","breadcrumb":{"@id":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.in2sa.cat\/es\/2022\/03\/01\/deseas-aprovechar-las-ayudas-de-digitalizacion-para-pymes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.in2sa.cat\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfDeseas aprovechar las ayudas de digitalizaci\u00f3n para Pymes?"}]},{"@type":"WebSite","@id":"https:\/\/www.in2sa.cat\/es\/#website","url":"https:\/\/www.in2sa.cat\/es\/","name":"IN2 - Inform\u00e1tica industrial","description":"Services for business","publisher":{"@id":"https:\/\/www.in2sa.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.in2sa.cat\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.in2sa.cat\/es\/#organization","name":"IN2 - Inform\u00e1tica industrial","url":"https:\/\/www.in2sa.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png","contentUrl":"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png","width":287,"height":64,"caption":"IN2 - Inform\u00e1tica industrial"},"image":{"@id":"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.in2sa.cat\/es\/#\/schema\/person\/4e69107c738f5383b8175d939415715f","name":"indosAdmin"}]}},"_links":{"self":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/posts\/1278"}],"collection":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/comments?post=1278"}],"version-history":[{"count":1,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/posts\/1278\/revisions"}],"predecessor-version":[{"id":1279,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/posts\/1278\/revisions\/1279"}],"wp:attachment":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/media?parent=1278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/categories?post=1278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/tags?post=1278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}