{"id":137,"date":"2019-02-03T18:00:08","date_gmt":"2019-02-03T17:00:08","guid":{"rendered":"https:\/\/www.in2sa.cat\/?page_id=137"},"modified":"2025-05-08T14:51:34","modified_gmt":"2025-05-08T13:51:34","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"\n<h1>Responsable del Tratamiento<\/h1>\n\n\n\n<p>La empresa responsable del tratamiento de sus datos en virtud de esta Pol\u00edtica de privacidad es: INFORM\u00c1TICA INDUSTRIAL IN2, S.A.<\/p>\n\n\n\n<p>NIF: A58193079<\/p>\n\n\n\n<p>Domicilio: Doctor Salv\u00e0, 148, bajos \u2013 (08224) TERRASSA &#8211; BARCELONA Direcci\u00f3n de correo electr\u00f3nico: <a href=\"mailto:rgpd@in2sa.cat\">rgpd@in2sa.cat<\/a><\/p>\n\n\n\n<p>Web: in2sa.cat\/ Tel\u00e9fono: 937331919<\/p>\n\n\n\n<p>Inscrita en el Registro Mercantil de Barcelona , tomo 7455, Libro 6723 Secci\u00f3n 2&#8243;, Folio 129 Hoja 85657, Insc 1a<\/p>\n\n\n\n<p>En INFORMATICA INDUSTRIAL IN2, S.A., reconocemos la importancia de proteger su informaci\u00f3n personal y estamos comprometidos a tratarla con responsabilidad y de conformidad con las leyes de protecci\u00f3n de datos.<\/p>\n\n\n\n<p>La presente pol\u00edtica de privacidad pretende regular todos los aspectos relativos al tratamiento de datos de los diferentes usuarios que navegan o facilitan sus datos personales a trav\u00e9s de los diferentes formularios situados en la web.<\/p>\n\n\n\n<h1>Datos Personales<\/h1>\n\n\n\n<p>Un dato personal es la informaci\u00f3n que le identifica o le hace identificable. A trav\u00e9s de la web, en las casillas establecidas al efecto recogemos los datos personales que el usuario nos comunica: nombre, apellidos, correo electr\u00f3nico, tel\u00e9fono, direcci\u00f3n postal, poblaci\u00f3n, etc., as\u00ed como todos aquellos datos que voluntariamente nos proporcione a trav\u00e9s de cualquier de las redes sociales de las cuales el usuario est\u00e1 registrado. En este caso, la privacidad depender\u00e1 de la propia configuraci\u00f3n establecida por el usuario as\u00ed como de los t\u00e9rminos y condiciones de la propia red social.<\/p>\n\n\n\n<p>La visita del usuario a la web no implica que tenga que facilitar ninguna informaci\u00f3n sobre sus datos personales. No obstante, en caso de facilitarlos, los datos ser\u00e1n tratados de forma l\u00edcita con sujeci\u00f3n en todo momento a los principios y derechos recogidos en el RGPD 2016\/679 de 27 de abril de 2016 y la LOPDGDD 3\/2018 del 5 de diciembre.<\/p>\n\n\n\n<h1>Finalidad, duraci\u00f3n y legitimaci\u00f3n del tratamiento:<\/h1>\n\n\n\n<p>Los datos que el usuario nos proporcione los trataremos con las siguientes finalidades:<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" src=\"\" width=\"5\" height=\"5\"> Mejorar su experiencia al navegar por la web. Estos datos los conservaremos mientras el usuario no revoque su consentimiento al tratamiento de los mismos eliminando las cookies y durante el tiempo establecido por la ley con una duraci\u00f3n m\u00ednima de 3 a\u00f1os.<\/p>\n\n\n\n<p>La base de legitimaci\u00f3n para mejorar su experiencia al navegar por la web es el consentimiento que otorga el usuario al aceptar las cookies. El usuario tiene derecho a revocar su consentimiento en cualquier momento sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" src=\"\" width=\"5\" height=\"5\"> Gestionar nuestras <strong>redes sociales <\/strong>y enviarle informaci\u00f3n sobre nuestras actividades y productos. Estos datos los conservaremos mientras el usuario no revoque su consentimiento al tratamiento de los mismos y durante el tiempo establecido por la ley con una duraci\u00f3n m\u00ednima de 3 a\u00f1os.<\/p>\n\n\n\n<p>La base leg\u00edtima para gestionar nuestras redes sociales y enviarle nuestras actividades y novedades es el consentimiento que nos otorga para ello. El usuario tiene derecho a revocar su consentimiento en cualquier momento sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" src=\"\" width=\"5\" height=\"5\"> Gestionar el <strong>curr\u00edculum <\/strong>remitido por la persona interesada a trav\u00e9s del formulario habilitado para tal efecto e incluirlo en la base de datos de candidatos de la empresa. Estos datos se tratar\u00e1n durante el plazo m\u00e1ximo de un a\u00f1o, transcurrido el cual, se proceder\u00e1 al bloqueo de los datos durante el tiempo establecido legalmente, garantiz\u00e1ndole un total respeto a la confidencialidad tanto en el tratamiento como en su posterior destrucci\u00f3n.<\/p>\n\n\n\n<p>La base leg\u00edtima para gestionar y tratar el curr\u00edculum de la persona interesada es su consentimiento el cual manifiesta al realizar una acci\u00f3n afirmativa de env\u00edo del mismo y seleccionar la casilla de aceptaci\u00f3n de nuestra pol\u00edtica de privacidad previamente a su env\u00edo. El usuario tiene derecho a revocar su consentimiento en cualquier momento sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada.<\/p>\n\n\n\n<h1>Cesi\u00f3n o comunicaci\u00f3n de datos personales y transferencias internacionales<\/h1>\n\n\n\n<p>Sus datos no se comunicar\u00e1n ni ser\u00e1n cedidos a terceros, salvo que exista alguna obligaci\u00f3n legal o aquellos prestadores vinculados al Responsable que act\u00faan como encargados del tratamiento.<\/p>\n\n\n\n<p>\u200bNuestros servidores est\u00e1n ubicados en la Uni\u00f3n Europea, y con car\u00e1cter general, contratamos prestadores de servicios ubicados tambi\u00e9n dentro del Espacio Econ\u00f3mico Europeo o en pa\u00edses que han sido declarados con un nivel adecuado de protecci\u00f3n.<\/p>\n\n\n\n<p>Si necesitamos utilizar proveedores de servicios externos que requieran la transmisi\u00f3n de datos personales fuera \u200bde \u200bla Uni\u00f3n Europea o en pa\u00edses que no han sido declarados con un nivel adecuado de protecci\u00f3n, nos aseguraremos de garantizar la seguridad y legitimidad del tratamiento de sus datos mediante decisiones de adecuaci\u00f3n, cl\u00e1usulas tipo, normas corporativas vinculantes, excepciones o cualquier otro instrumento aprobado por la autoridad de control que ofrezca las garant\u00edas adecuadas para la realizaci\u00f3n de la transferencia internacional de datos.<\/p>\n\n\n\n<h1>Actualizaci\u00f3n de datos<\/h1>\n\n\n\n<p>Es importante que para que podamos mantener los datos personales actualizados, el usuario nos informe siempre que haya habido alguna modificaci\u00f3n en ellos, en caso contrario, no respondemos de la veracidad de los mismos.<\/p>\n\n\n\n<p>El usuario garantiza que los datos personales facilitados son veraces garantizando que toda la informaci\u00f3n facilitada corresponde con la situaci\u00f3n real, que est\u00e1 actualizada y es exacta, quedando obligado a comunicar cualquier modificaci\u00f3n.<\/p>\n\n\n\n<h1>Datos de Terceros<\/h1>\n\n\n\n<p>Si el usuario facilita datos de terceras personas para cualquier finalidad a INFORMATICA INDUSTRIAL IN2, S.A., garantiza que ha obtenido estos datos de forma l\u00edcita, que ha informado previamente a los afectados, obteniendo su consentimiento para comunicarlos y que la informaci\u00f3n facilitada es exacta y veraz.<\/p>\n\n\n\n<h1>Car\u00e1cter obligatorio de la informaci\u00f3n solicitada<\/h1>\n\n\n\n<p>Todos nuestros formularios cuentan con un asterisco (*) en los datos obligatorios. Si el usuario no facilita esos campos, o no marca la casilla de aceptaci\u00f3n de la pol\u00edtica de privacidad, no se permitir\u00e1 el env\u00edo de la informaci\u00f3n.<\/p>\n\n\n\n<h1>Derechos de los las personas interesadas<\/h1>\n\n\n\n<p>Tiene derecho a acceder a sus datos y a obtener confirmaci\u00f3n sobre su tratamiento, as\u00ed como una copia de los datos personales objeto de tratamiento. Tiene derecho a actualizarlos y solicitar la rectificaci\u00f3n de los datos que sean inexactos o solicitar la supresi\u00f3n cuando los datos no sean necesarios para los fines para los que fueron recabados. Puede solicitar la limitaci\u00f3n en el tratamiento de sus datos y oponerse al tratamiento de los mismos revocando su consentimiento, as\u00ed como ejercer el derecho a la portabilidad de los datos. Del mismo modo, tiene derecho a no ser objeto de decisiones basadas \u00fanicamente en el tratamiento automatizado de sus datos personales. Puede ejercer sus derechos contactando con nosotros <a href=\"mailto:rgpd@in2sa.cat\">rgpd@in2sa.cat<\/a><\/p>\n\n\n\n<p>Si considera que sus derechos no se han atendido debidamente, tiene derecho a presentar una reclamaci\u00f3n ante la autoridad de control en <a href=\"http:\/\/www.aepd.es\/\">www.aepd.es.<\/a><\/p>\n\n\n\n<h1>Tratamiento de datos de Menores de edad<\/h1>\n\n\n\n<p>Quien facilita los datos a trav\u00e9s de los formularios de esta web y acepta su tratamiento declara ser mayor de 14 a\u00f1os, quedando prohibido el acceso y uso del portal a menores de dicha edad. Si en alg\u00fan momento, el Responsable detecta que un menor de 14 a\u00f1os ha proporcionado datos de car\u00e1cter personal, procederemos a la cancelaci\u00f3n de los mismos. Asimismo, los padres o tutores podr\u00e1n en cualquier caso dirigirse a INFORM\u00c1TICA INDUSTRIAL IN2, S.A. para bloquear la cuenta de acceso de los menores a su cargo que se hubieran registrado falseando su identidad.<\/p>\n\n\n\n<h1>Redes sociales<\/h1>\n\n\n\n<p>El objeto de las herramientas como Facebook, Twitter, Instagram, etc. u otras redes sociales es dar visibilidad y difusi\u00f3n a las actividades que desarrolla nuestra organizaci\u00f3n. Estas herramientas almacenan datos personales en los servidores de los servicios respectivos y se rigen por su propia pol\u00edtica de privacidad. Se recomienda la revisi\u00f3n y la lectura de las condiciones de uso y pol\u00edtica de privacidad de la red social en el momento de registrarse, teniendo en cuenta las diferentes posibilidades de configuraci\u00f3n en relaci\u00f3n al grado de privacidad del perfil de usuario en la red social.<\/p>\n\n\n\n<p>Asimismo, el Responsable se reserva el derecho de eliminar de sus redes sociales cualquier informaci\u00f3n publicada por terceros que vulnere la legalidad, incite a hacerlo o contenga mensajes que atenten contra la dignidad de personas o instituciones. Como tambi\u00e9n el derecho a bloquear o denunciar el perfil autor de estos mensajes.<\/p>\n\n\n\n<h1>Tratamiento de Cookies<\/h1>\n\n\n\n<p>Una cookie es un peque\u00f1o archivo que se descarga y almacena en el ordenador del usuario cuando este accede a una p\u00e1gina web. Las Cookies permiten a la web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n del usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario.<\/p>\n\n\n\n<p>El usuario tiene la opci\u00f3n de impedir la generaci\u00f3n de cookies, mediante la selecci\u00f3n de la correspondiente opci\u00f3n en su programa de navegador. Puede obtener m\u00e1s informaci\u00f3n leyendo nuestra <a href=\"https:\/\/www.in2sa.cat\/es\/politica-de-cookies\/\">Pol\u00edtica de Cookies<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Responsable del Tratamiento La empresa responsable del tratamiento de sus datos en virtud de esta Pol\u00edtica de privacidad es: INFORM\u00c1TICA INDUSTRIAL IN2, S.A. NIF: A58193079 Domicilio: Doctor Salv\u00e0, 148, bajos \u2013 (08224) TERRASSA &#8211; BARCELONA Direcci\u00f3n de correo electr\u00f3nico: rgpd@in2sa.cat Web: in2sa.cat\/ Tel\u00e9fono: 937331919 Inscrita en el Registro Mercantil de Barcelona , tomo 7455, Libro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":100,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de privacidad - IN2 - Inform\u00e1tica industrial<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - IN2 - Inform\u00e1tica industrial\" \/>\n<meta property=\"og:description\" content=\"Responsable del Tratamiento La empresa responsable del tratamiento de sus datos en virtud de esta Pol\u00edtica de privacidad es: INFORM\u00c1TICA INDUSTRIAL IN2, S.A. NIF: A58193079 Domicilio: Doctor Salv\u00e0, 148, bajos \u2013 (08224) TERRASSA &#8211; BARCELONA Direcci\u00f3n de correo electr\u00f3nico: rgpd@in2sa.cat Web: in2sa.cat\/ Tel\u00e9fono: 937331919 Inscrita en el Registro Mercantil de Barcelona , tomo 7455, Libro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"IN2 - Inform\u00e1tica industrial\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T13:51:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/\",\"url\":\"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de privacidad - IN2 - Inform\u00e1tica industrial\",\"isPartOf\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#website\"},\"datePublished\":\"2019-02-03T17:00:08+00:00\",\"dateModified\":\"2025-05-08T13:51:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.in2sa.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#website\",\"url\":\"https:\/\/www.in2sa.cat\/es\/\",\"name\":\"IN2 - Inform\u00e1tica industrial\",\"description\":\"Services for business\",\"publisher\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.in2sa.cat\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#organization\",\"name\":\"IN2 - Inform\u00e1tica industrial\",\"url\":\"https:\/\/www.in2sa.cat\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png\",\"contentUrl\":\"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png\",\"width\":287,\"height\":64,\"caption\":\"IN2 - Inform\u00e1tica industrial\"},\"image\":{\"@id\":\"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - IN2 - Inform\u00e1tica industrial","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad - IN2 - Inform\u00e1tica industrial","og_description":"Responsable del Tratamiento La empresa responsable del tratamiento de sus datos en virtud de esta Pol\u00edtica de privacidad es: INFORM\u00c1TICA INDUSTRIAL IN2, S.A. NIF: A58193079 Domicilio: Doctor Salv\u00e0, 148, bajos \u2013 (08224) TERRASSA &#8211; BARCELONA Direcci\u00f3n de correo electr\u00f3nico: rgpd@in2sa.cat Web: in2sa.cat\/ Tel\u00e9fono: 937331919 Inscrita en el Registro Mercantil de Barcelona , tomo 7455, Libro [&hellip;]","og_url":"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/","og_site_name":"IN2 - Inform\u00e1tica industrial","article_modified_time":"2025-05-08T13:51:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/","url":"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad - IN2 - Inform\u00e1tica industrial","isPartOf":{"@id":"https:\/\/www.in2sa.cat\/es\/#website"},"datePublished":"2019-02-03T17:00:08+00:00","dateModified":"2025-05-08T13:51:34+00:00","breadcrumb":{"@id":"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.in2sa.cat\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.in2sa.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/www.in2sa.cat\/es\/#website","url":"https:\/\/www.in2sa.cat\/es\/","name":"IN2 - Inform\u00e1tica industrial","description":"Services for business","publisher":{"@id":"https:\/\/www.in2sa.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.in2sa.cat\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.in2sa.cat\/es\/#organization","name":"IN2 - Inform\u00e1tica industrial","url":"https:\/\/www.in2sa.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png","contentUrl":"https:\/\/www.in2sa.cat\/wp-content\/uploads\/2019\/02\/logo.png","width":287,"height":64,"caption":"IN2 - Inform\u00e1tica industrial"},"image":{"@id":"https:\/\/www.in2sa.cat\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/pages\/137"}],"collection":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":7,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/pages\/137\/revisions"}],"predecessor-version":[{"id":2816,"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/pages\/137\/revisions\/2816"}],"wp:attachment":[{"href":"https:\/\/www.in2sa.cat\/es\/wp-json\/wp\/v2\/media?parent=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}